{"id":2964,"date":"2026-02-06T15:40:21","date_gmt":"2026-02-06T13:40:21","guid":{"rendered":"https:\/\/hocus.lt\/?page_id=2964"},"modified":"2026-02-09T13:11:02","modified_gmt":"2026-02-09T13:11:02","slug":"50-discount","status":"publish","type":"page","link":"https:\/\/old.hocus.lt\/en\/50-discount\/","title":{"rendered":"50% Discount"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-promo-new-clients.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2964","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>50% Discount - Hocus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/old.hocus.lt\/en\/50-discount\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"50% Discount - Hocus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/old.hocus.lt\/en\/50-discount\/\" \/>\n<meta property=\"og:site_name\" content=\"Hocus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/hocuslt\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T13:11:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@byhocus\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/old.hocus.lt\/en\/50-discount\/\",\"url\":\"https:\/\/old.hocus.lt\/en\/50-discount\/\",\"name\":\"50% Discount - Hocus\",\"isPartOf\":{\"@id\":\"https:\/\/old.hocus.lt\/en\/#website\"},\"datePublished\":\"2026-02-06T13:40:21+00:00\",\"dateModified\":\"2026-02-09T13:11:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/old.hocus.lt\/en\/50-discount\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/old.hocus.lt\/en\/50-discount\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/old.hocus.lt\/en\/50-discount\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/old.hocus.lt\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"50% Discount\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/old.hocus.lt\/en\/#website\",\"url\":\"https:\/\/old.hocus.lt\/en\/\",\"name\":\"Hocus\",\"description\":\"Handcrafted Perfection. No Machines. Just Pure Clean.\",\"publisher\":{\"@id\":\"https:\/\/old.hocus.lt\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/old.hocus.lt\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/old.hocus.lt\/en\/#organization\",\"name\":\"Hocus\",\"url\":\"https:\/\/old.hocus.lt\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/old.hocus.lt\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hocus.lt\/wp-content\/uploads\/2025\/06\/hocus-logo-1.svg\",\"contentUrl\":\"https:\/\/hocus.lt\/wp-content\/uploads\/2025\/06\/hocus-logo-1.svg\",\"width\":225,\"height\":59,\"caption\":\"Hocus\"},\"image\":{\"@id\":\"https:\/\/old.hocus.lt\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/hocuslt\",\"https:\/\/x.com\/byhocus\",\"https:\/\/www.instagram.com\/hocus.lt\/\",\"https:\/\/www.tiktok.com\/@hocus.lt\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"50% Discount - Hocus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/old.hocus.lt\/en\/50-discount\/","og_locale":"en_US","og_type":"article","og_title":"50% Discount - Hocus","og_url":"https:\/\/old.hocus.lt\/en\/50-discount\/","og_site_name":"Hocus","article_publisher":"https:\/\/www.facebook.com\/hocuslt","article_modified_time":"2026-02-09T13:11:02+00:00","twitter_card":"summary_large_image","twitter_site":"@byhocus","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/old.hocus.lt\/en\/50-discount\/","url":"https:\/\/old.hocus.lt\/en\/50-discount\/","name":"50% Discount - Hocus","isPartOf":{"@id":"https:\/\/old.hocus.lt\/en\/#website"},"datePublished":"2026-02-06T13:40:21+00:00","dateModified":"2026-02-09T13:11:02+00:00","breadcrumb":{"@id":"https:\/\/old.hocus.lt\/en\/50-discount\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/old.hocus.lt\/en\/50-discount\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/old.hocus.lt\/en\/50-discount\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/old.hocus.lt\/en\/"},{"@type":"ListItem","position":2,"name":"50% Discount"}]},{"@type":"WebSite","@id":"https:\/\/old.hocus.lt\/en\/#website","url":"https:\/\/old.hocus.lt\/en\/","name":"Hocus","description":"Handcrafted Perfection. No Machines. Just Pure Clean.","publisher":{"@id":"https:\/\/old.hocus.lt\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/old.hocus.lt\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/old.hocus.lt\/en\/#organization","name":"Hocus","url":"https:\/\/old.hocus.lt\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/old.hocus.lt\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hocus.lt\/wp-content\/uploads\/2025\/06\/hocus-logo-1.svg","contentUrl":"https:\/\/hocus.lt\/wp-content\/uploads\/2025\/06\/hocus-logo-1.svg","width":225,"height":59,"caption":"Hocus"},"image":{"@id":"https:\/\/old.hocus.lt\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/hocuslt","https:\/\/x.com\/byhocus","https:\/\/www.instagram.com\/hocus.lt\/","https:\/\/www.tiktok.com\/@hocus.lt"]}]}},"_links":{"self":[{"href":"https:\/\/old.hocus.lt\/en\/wp-json\/wp\/v2\/pages\/2964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/old.hocus.lt\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/old.hocus.lt\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/old.hocus.lt\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/old.hocus.lt\/en\/wp-json\/wp\/v2\/comments?post=2964"}],"version-history":[{"count":6,"href":"https:\/\/old.hocus.lt\/en\/wp-json\/wp\/v2\/pages\/2964\/revisions"}],"predecessor-version":[{"id":3077,"href":"https:\/\/old.hocus.lt\/en\/wp-json\/wp\/v2\/pages\/2964\/revisions\/3077"}],"wp:attachment":[{"href":"https:\/\/old.hocus.lt\/en\/wp-json\/wp\/v2\/media?parent=2964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}